{"id":41863,"date":"2024-10-30T01:00:22","date_gmt":"2024-10-30T04:00:22","guid":{"rendered":"https:\/\/aprendizdomundo.com\/portal\/?p=41863"},"modified":"2024-10-05T19:39:29","modified_gmt":"2024-10-05T22:39:29","slug":"memoriabrasil1225","status":"publish","type":"post","link":"https:\/\/aprendizdomundo.com\/portal\/2024\/10\/30\/memoriabrasil1225\/","title":{"rendered":"Ary Barroso na Universidade AM nesta quarta, 30\/10"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" title=\"Ary Barroso\" src=\"https:\/\/aprendizdomundo.com\/imagens\/mb_arybarroso.jpg\" alt=\"Ary Barroso\" width=\"320\" height=\"320\" \/>Acompanhe o <strong>Mem\u00f3ria Brasil<\/strong> de hoje, a partir das <strong>11h00<\/strong>, pela <strong><a title=\"R\u00e1dio Universidade AM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Universidade AM<\/a><\/strong>.<\/p>\n<p>A audi\u00e7\u00e3o desta manh\u00e3 destaca a obra de <strong>Ary Barroso<\/strong>, na voz de cantoras brasileiras. Compositor, pianista e radialista, Ary de Resende Barroso nasceu a 7 de novembro de 1903, no munic\u00edpio mineiro de Ub\u00e1, e morreu a 9 de fevereiro de 1964, na cidade do Rio de Janeiro.<\/p>\n<p><strong><a title=\"Mem\u00f3ria Brasil\" href=\"https:\/\/aprendizdomundo.com\/portal\/radio\/programas\/memoria\/\">Mem\u00f3ria Brasil<\/a><\/strong> \u00e9 um programa cultural dedicado \u00e0 veicula\u00e7\u00e3o da m\u00fasica popular brasileira, valorizando seus principais compositores e int\u00e9rpretes, no formato tem\u00e1tico, destacando um tema ou compositor ou int\u00e9rprete a cada audi\u00e7\u00e3o.<\/p>\n<p>A atra\u00e7\u00e3o vai ao ar pela <strong>Universidade AM<\/strong>, de segunda a sexta, na faixa das 11h00 \u00e0s 12h00. A pesquisa, produ\u00e7\u00e3o, sele\u00e7\u00e3o de repert\u00f3rio, reda\u00e7\u00e3o de texto, apresenta\u00e7\u00e3o e edi\u00e7\u00e3o \u00e9 de <strong><a title=\"Milton Oliveira\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/aprendizdomundo.com\/miltonoliveira\">Milton Oliveira<\/a><\/strong>.<\/p>\n<p>O programa pode ser ouvido pelos <strong>800 AM<\/strong>, pelo <strong><a title=\"R\u00e1dio Universidade AM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">site da emissora<\/a><\/strong> ou pelo smartphone, acessando seu aplicativo favorito.<\/p>\n<p>O <strong>Mem\u00f3ria Brasil<\/strong> tamb\u00e9m \u00e9 veiculado pela <strong><a title=\"R\u00e1dio Uni FM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">Uni FM 107.9<\/a><\/strong>, todo domingo, na faixa das 13h00 \u00e0s 14h00; pela <strong><a title=\"R\u00e1dio Bloco\" href=\"http:\/\/www.radiobloco.net\/\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Bloco<\/a><\/strong>, toda quarta, na faixa das 17h00 \u00e0s 18h00; pela <strong><a title=\"R\u00e1dio UFSCar FM 95.3\" href=\"https:\/\/www.radio.ufscar.br\/\" target=\"_blank\" rel=\"noopener\">UFSCar FM 95.3<\/a><\/strong>, toda quarta, na faixa das 22h00 \u00e0s 23h00; e pela <strong><a title=\"Resonance R\u00e1dio\" href=\"http:\/\/www.resonanceradio.com.br\/\" target=\"_blank\" rel=\"noopener\">Resonance R\u00e1dio<\/a><\/strong>, toda sexta, na faixa das 20h00 \u00e0s 21h00. As audi\u00e7\u00f5es n\u00e3o s\u00e3o vinculadas, os destaques s\u00e3o sempre diferentes em cada emissora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompanhe o Mem\u00f3ria Brasil de hoje, a partir das 11h00, pela R\u00e1dio Universidade AM. A audi\u00e7\u00e3o desta manh\u00e3 destaca a obra de Ary Barroso, na voz de cantoras brasileiras. Compositor, pianista e radialista, Ary de Resende Barroso nasceu a 7 de novembro de 1903, no munic\u00edpio mineiro de Ub\u00e1, e morreu a 9 de fevereiro [&#8230;] <\/p>\n<p class=\"more-link-container\"><a href=\"https:\/\/aprendizdomundo.com\/portal\/2024\/10\/30\/memoriabrasil1225\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> &#8220;Ary Barroso na Universidade AM nesta quarta, 30\/10&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":42374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[17],"tags":[47],"class_list":["post-41863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memoria","tag-memoriabrasil"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/41863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/comments?post=41863"}],"version-history":[{"count":1,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/41863\/revisions"}],"predecessor-version":[{"id":41864,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/41863\/revisions\/41864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/media\/42374"}],"wp:attachment":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/media?parent=41863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/categories?post=41863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/tags?post=41863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}