{"id":52894,"date":"2026-02-10T08:00:23","date_gmt":"2026-02-10T11:00:23","guid":{"rendered":"https:\/\/aprendizdomundo.com\/portal\/?p=52894"},"modified":"2026-02-14T10:26:22","modified_gmt":"2026-02-14T13:26:22","slug":"aquarelanaresonance493","status":"publish","type":"post","link":"https:\/\/aprendizdomundo.com\/portal\/2026\/02\/10\/aquarelanaresonance493\/","title":{"rendered":"Aquarela em destaque na Resonance nesta ter\u00e7a, 10\/02"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" title=\"Aquarela\" src=\"https:\/\/aprendizdomundo.com\/imagens\/marca800_aquarela_resonance2.png\" alt=\"Aquarela\" width=\"320\" height=\"320\" \/>Acompanhe o <strong><a title=\"Aquarela\" href=\"https:\/\/aprendizdomundo.com\/portal\/radio\/programas\/aquarela\/\">Aquarela<\/a><\/strong>, a partir das 22h00, pela <strong>Resonance R\u00e1dio<\/strong>. Uma produ\u00e7\u00e3o original da <strong><a title=\"R\u00e1dio Universidade AM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Universidade AM<\/a><\/strong>.<\/p>\n<p>O repert\u00f3rio desta semana viaja pelos sons de, entre outros, Victor Assis Brasil, Quinteto da Para\u00edba, Jo\u00e3o Donato, Egberto Gismonti, Cesar Camargo Mariano e H\u00e9lio Delmiro, Uakti, Laurindo Almeida e The Bossa Nova all Stars, Milton Banana Trio e Quarteto Gauderiando.<\/p>\n<p><strong>Aquarela<\/strong> \u00e9 um programa especializado em m\u00fasica instrumental criada e\/ou executada por instrumentistas, grupos instrumentais ou orquestras do Brasil.<\/p>\n<p>A atra\u00e7\u00e3o vai ao ar pela <strong><a title=\"Resonance R\u00e1dio\" href=\"http:\/\/www.resonanceradio.com.br\/\" target=\"_blank\" rel=\"noopener\">Resonance R\u00e1dio<\/a><\/strong> toda ter\u00e7a, na faixa das 22h00 \u00e0s 23h00. A produ\u00e7\u00e3o, sele\u00e7\u00e3o de repert\u00f3rio, reda\u00e7\u00e3o de texto, apresenta\u00e7\u00e3o e edi\u00e7\u00e3o \u00e9 de <strong><a title=\"Links de Milton Oliveira\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/apptuts.bio\/miltonoliveira\">Milton Oliveira<\/a><\/strong>.<\/p>\n<p>O programa pode ser ouvido pela home page da emissora, em <strong><a title=\"Resonance R\u00e1dio\" href=\"http:\/\/www.resonanceradio.com.br\/\" target=\"_blank\" rel=\"noopener\">www.resonanceradio.com.br<\/a><\/strong>, ou pelo smartphone, acessando seu aplicativo favorito.<\/p>\n<p>O <strong>Aquarela<\/strong> tamb\u00e9m \u00e9 veiculado pela <strong><a title=\"R\u00e1dio Universidade AM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">Universidade 800 AM<\/a><\/strong>, no domingo, na faixa das 11h00 \u00e0s 12h00; e pela <strong><a title=\"R\u00e1dio Uni FM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">Uni FM 107.9<\/a><\/strong>, no s\u00e1bado, na faixa das 12h00 \u00e0s 13h00. As audi\u00e7\u00f5es n\u00e3o s\u00e3o vinculadas, os destaques s\u00e3o sempre diferentes em cada emissora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompanhe o Aquarela, a partir das 22h00, pela Resonance R\u00e1dio. Uma produ\u00e7\u00e3o original da R\u00e1dio Universidade AM. O repert\u00f3rio desta semana viaja pelos sons de, entre outros, Victor Assis Brasil, Quinteto da Para\u00edba, Jo\u00e3o Donato, Egberto Gismonti, Cesar Camargo Mariano e H\u00e9lio Delmiro, Uakti, Laurindo Almeida e The Bossa Nova all Stars, Milton Banana Trio [&#8230;] <\/p>\n<p class=\"more-link-container\"><a href=\"https:\/\/aprendizdomundo.com\/portal\/2026\/02\/10\/aquarelanaresonance493\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> &#8220;Aquarela em destaque na Resonance nesta ter\u00e7a, 10\/02&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":52893,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[2],"tags":[122,41],"class_list":["post-52894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquarela","tag-aquarela-2","tag-aquarela"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/52894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/comments?post=52894"}],"version-history":[{"count":3,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/52894\/revisions"}],"predecessor-version":[{"id":53655,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/52894\/revisions\/53655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/media\/52893"}],"wp:attachment":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/media?parent=52894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/categories?post=52894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/tags?post=52894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}