{"id":53530,"date":"2026-02-10T19:00:15","date_gmt":"2026-02-10T22:00:15","guid":{"rendered":"https:\/\/aprendizdomundo.com\/portal\/?p=53530"},"modified":"2026-02-09T09:34:43","modified_gmt":"2026-02-09T12:34:43","slug":"sarandeio3217","status":"publish","type":"post","link":"https:\/\/aprendizdomundo.com\/portal\/2026\/02\/10\/sarandeio3217\/","title":{"rendered":"Sarandeio no amanhecer da Universidade AM, 11\/02"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" title=\"Sarandeio\" src=\"https:\/\/aprendizdomundo.com\/imagens\/sarandeio_d01.png\" alt=\"Sarandeio\" width=\"320\" height=\"320\" \/>Acompanhe o <strong>Sarandeio<\/strong> na pr\u00f3xima madrugada, a partir das <strong>05h00<\/strong>, pela <strong><a title=\"R\u00e1dio Universidade AM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Universidade AM<\/a><\/strong>.<\/p>\n<p>A sele\u00e7\u00e3o musical vai destacar&#8230;<\/p>\n<p>Ga\u00facho Guapo &#8211; Marcas<br \/>\nGrupo Chama Campeira &#8211; Sina Que Herdei<br \/>\nOs Santannas &#8211; Sou Guapo<br \/>\nWilson Paim &#8211; Na Solid\u00e3o da Campanha<br \/>\nJo\u00e3o Chagas Leite &#8211; Ave Sonora, em vers\u00e3o ao vivo<br \/>\nMano Monteiro &#8211; A Villa Guillermina<br \/>\nEco do Minuano e Bonitinho &#8211; Ga\u00facho Cento por Cento<br \/>\nCristiano Quevedo &#8211; A \u00daltima Flor do Rancho<br \/>\nGrupo Oiga Tch\u00ea &#8211; Roda a Saia<br \/>\nRui Biriva &#8211; Barbaridade<br \/>\nOs Serranos &#8211; Tropeiro de Rimas<br \/>\nXir\u00fa Missioneiro &#8211; Amor de Atravessado<br \/>\nOs Rancheiros \u2013 Rodeio, Cantiga e Cordeona<br \/>\nAdriano Ineu &#8211; O Solu\u00e7o do Bugio<br \/>\nExpresso Tch\u00ea &#8211; Pra Ouvir o Som<br \/>\nAnt\u00f4nio Gringo &#8211; Cativeiros<br \/>\nOs Fagundes &#8211; A Gente Canta<br \/>\nGa\u00facho da Fronteira &#8211; O Candidato<br \/>\nQuer\u00eancia Xucra &#8211; Gineteando Destinos<br \/>\nMeio Kilo &#8211; De Causos e Gauchadas<br \/>\nGrupo Rodeio &#8211; De P\u00e9 no Estribo<br \/>\nAninha Pires &#8211; Nas Patas do Meu Cavalo<br \/>\nJo\u00e3o Luiz Corr\u00eaa &#8211; No Rinc\u00e3o do Risca-Faca<br \/>\nEstouro Ga\u00facho &#8211; Rancho Tapera<br \/>\nOs Araganos &#8211; Cancha Livre<br \/>\nPiazitos do Fandango &#8211; Pra Quem Tem Raiz<br \/>\nLuiz dos Reis &#8211; No Tranco da Vaneira<br \/>\nGrupo Ra\u00edzes &#8211; Cortando Estado<br \/>\nEdilberto B\u00e9rgamo &#8211; El Toro<br \/>\nGrupo Santo Ch\u00e3o &#8211; Pe\u00e3o Campeiro<br \/>\nBochincho &#8211; Baixinho no Bail\u00e3o<\/p>\n<p><strong><a title=\"Sarandeio\" href=\"https:\/\/aprendizdomundo.com\/portal\/radio\/programas\/sarandeio\/\">Sarandeio<\/a><\/strong> \u00e9 um programa dedicado \u00e0 m\u00fasica ga\u00facha, especialmente a vertente fandangueira. Re\u00fane can\u00e7\u00f5es de int\u00e9rpretes e grupos do Rio Grande do Sul e, tamb\u00e9m, artistas de outros estados que igualmente produzem m\u00fasica fandangueira.<\/p>\n<p>A atra\u00e7\u00e3o vai ao ar pela <strong>Universidade AM<\/strong>, todos os dias, na faixa das 05h00 \u00e0s 07h00. A pesquisa, produ\u00e7\u00e3o, sele\u00e7\u00e3o de repert\u00f3rio e edi\u00e7\u00e3o \u00e9 de <strong><a title=\"Milton Oliveira\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/aprendizdomundo.com\/miltonoliveira\">Milton Oliveira<\/a><\/strong>.<\/p>\n<p>O programa pode ser ouvido pelos <strong>800 AM<\/strong>, pelo <strong><a title=\"R\u00e1dio Universidade AM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">site da emissora<\/a><\/strong> ou pelo smartphone, acessando seu aplicativo favorito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompanhe o Sarandeio na pr\u00f3xima madrugada, a partir das 05h00, pela R\u00e1dio Universidade AM. A sele\u00e7\u00e3o musical vai destacar&#8230; Ga\u00facho Guapo &#8211; Marcas Grupo Chama Campeira &#8211; Sina Que Herdei Os Santannas &#8211; Sou Guapo Wilson Paim &#8211; Na Solid\u00e3o da Campanha Jo\u00e3o Chagas Leite &#8211; Ave Sonora, em vers\u00e3o ao vivo Mano Monteiro &#8211; [&#8230;] <\/p>\n<p class=\"more-link-container\"><a href=\"https:\/\/aprendizdomundo.com\/portal\/2026\/02\/10\/sarandeio3217\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> &#8220;Sarandeio no amanhecer da Universidade AM, 11\/02&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":52880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[22],"tags":[51,133],"class_list":["post-53530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sarandeio","tag-sarandeio","tag-sarandeio2"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/53530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/comments?post=53530"}],"version-history":[{"count":1,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/53530\/revisions"}],"predecessor-version":[{"id":53531,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/53530\/revisions\/53531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/media\/52880"}],"wp:attachment":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/media?parent=53530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/categories?post=53530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/tags?post=53530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}