{"id":55831,"date":"2026-05-13T01:00:46","date_gmt":"2026-05-13T04:00:46","guid":{"rendered":"https:\/\/aprendizdomundo.com\/portal\/?p=55831"},"modified":"2026-05-07T16:49:17","modified_gmt":"2026-05-07T19:49:17","slug":"memoriabrasil1665","status":"publish","type":"post","link":"https:\/\/aprendizdomundo.com\/portal\/2026\/05\/13\/memoriabrasil1665\/","title":{"rendered":"Sandra de S\u00e1 na Universidade AM nesta quarta, 13\/05"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" title=\"Sandra de S\u00e1\" src=\"https:\/\/aprendizdomundo.com\/imagens\/mb_sandradesa.jpg\" alt=\"Sandra de S\u00e1\" width=\"320\" height=\"320\" \/>Acompanhe o <strong>Mem\u00f3ria Brasil<\/strong> de hoje, a partir das <strong>11h00<\/strong>, pela <strong><a title=\"R\u00e1dio Universidade AM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Universidade AM<\/a><\/strong>.<\/p>\n<p>A audi\u00e7\u00e3o desta manh\u00e3 destaca <strong>Sandra de S\u00e1<\/strong>. Sandra Cristina Frederico de S\u00e1 nasceu a 27 de agosto de 1955, na cidade do Rio de Janeiro. Cantora e compositora, expoente da m\u00fasica popular brasileira, tem seu trabalho fortemente calcado na black music. Fez sua estreia em disco em 1980, com o lan\u00e7amento do \u00e1lbum Dem\u00f4nio Colorido.<\/p>\n<p><strong><a title=\"Mem\u00f3ria Brasil\" href=\"https:\/\/aprendizdomundo.com\/portal\/perfil_memoriabrasil\/\">Mem\u00f3ria Brasil<\/a><\/strong> \u00e9 um programa cultural dedicado \u00e0 veicula\u00e7\u00e3o da m\u00fasica popular brasileira, valorizando seus principais compositores e int\u00e9rpretes, no formato tem\u00e1tico, destacando um tema ou compositor ou int\u00e9rprete a cada audi\u00e7\u00e3o.<\/p>\n<p>A atra\u00e7\u00e3o vai ao ar pela <strong>Universidade AM<\/strong>, de segunda a sexta, na faixa das 11h00 \u00e0s 12h00. A pesquisa, produ\u00e7\u00e3o, sele\u00e7\u00e3o de repert\u00f3rio, reda\u00e7\u00e3o de texto, apresenta\u00e7\u00e3o e edi\u00e7\u00e3o \u00e9 de <strong><a title=\"Milton Oliveira\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/aprendizdomundo.com\/miltonoliveira\">Milton Oliveira<\/a><\/strong>.<\/p>\n<p>O programa pode ser ouvido pelos <strong>800 AM<\/strong>, pelo <strong><a title=\"R\u00e1dio Universidade AM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">site da emissora<\/a><\/strong> ou pelo smartphone, acessando seu aplicativo favorito.<\/p>\n<p>O <strong>Mem\u00f3ria Brasil<\/strong> tamb\u00e9m \u00e9 veiculado pela <strong><a title=\"R\u00e1dio Uni FM\" href=\"https:\/\/www.ufsm.br\/radio\" target=\"_blank\" rel=\"noopener\">Uni FM 107.9<\/a><\/strong>, todo domingo, na faixa das 13h00 \u00e0s 14h00; pela <strong><a title=\"R\u00e1dio Bloco\" href=\"http:\/\/www.radiobloco.net\/\" target=\"_blank\" rel=\"noopener\">R\u00e1dio Bloco<\/a><\/strong>, toda quarta, na faixa das 17h00 \u00e0s 18h00; pela <strong><a title=\"R\u00e1dio UFSCar FM 95.3\" href=\"https:\/\/www.radio.ufscar.br\/\" target=\"_blank\" rel=\"noopener\">UFSCar FM 95.3<\/a><\/strong>, toda quarta, na faixa das 21h00 \u00e0s 22h00; e pela <strong><a title=\"Resonance R\u00e1dio\" href=\"http:\/\/www.resonanceradio.com.br\/\" target=\"_blank\" rel=\"noopener\">Resonance R\u00e1dio<\/a><\/strong>, toda sexta, na faixa das 20h00 \u00e0s 21h00. As audi\u00e7\u00f5es n\u00e3o s\u00e3o vinculadas, os destaques s\u00e3o sempre diferentes em cada emissora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompanhe o Mem\u00f3ria Brasil de hoje, a partir das 11h00, pela R\u00e1dio Universidade AM. A audi\u00e7\u00e3o desta manh\u00e3 destaca Sandra de S\u00e1. Sandra Cristina Frederico de S\u00e1 nasceu a 27 de agosto de 1955, na cidade do Rio de Janeiro. Cantora e compositora, expoente da m\u00fasica popular brasileira, tem seu trabalho fortemente calcado na black [&#8230;] <\/p>\n<p class=\"more-link-container\"><a href=\"https:\/\/aprendizdomundo.com\/portal\/2026\/05\/13\/memoriabrasil1665\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> &#8220;Sandra de S\u00e1 na Universidade AM nesta quarta, 13\/05&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":52883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[17],"tags":[130,47],"class_list":["post-55831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memoria","tag-memoria-brasil","tag-memoriabrasil"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/55831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/comments?post=55831"}],"version-history":[{"count":1,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/55831\/revisions"}],"predecessor-version":[{"id":55832,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/posts\/55831\/revisions\/55832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/media\/52883"}],"wp:attachment":[{"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/media?parent=55831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/categories?post=55831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aprendizdomundo.com\/portal\/wp-json\/wp\/v2\/tags?post=55831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}